{"id":1860,"count":3,"description":"","link":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/","name":"summer vacation","slug":"summer-vacation","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v21.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>summer vacation Archives - I See Me! Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"summer vacation Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/\" \/>\n<meta property=\"og:site_name\" content=\"I See Me! Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/\",\"url\":\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/\",\"name\":\"summer vacation Archives - I See Me! Blog\",\"isPartOf\":{\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wordpress.iseeme.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"summer vacation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#website\",\"url\":\"https:\/\/wordpress.iseeme.com\/blog\/\",\"name\":\"I See Me! Blog\",\"description\":\"Personalized books for kids!\",\"publisher\":{\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wordpress.iseeme.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#organization\",\"name\":\"I See Me! Blog\",\"url\":\"https:\/\/wordpress.iseeme.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wordpress.iseeme.com\/wp-content\/uploads\/2023\/08\/ism_logo_500.png\",\"contentUrl\":\"https:\/\/wordpress.iseeme.com\/wp-content\/uploads\/2023\/08\/ism_logo_500.png\",\"width\":512,\"height\":512,\"caption\":\"I See Me! Blog\"},\"image\":{\"@id\":\"https:\/\/wordpress.iseeme.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ISeeMeBooks\",\"https:\/\/www.instagram.com\/iseemebooks\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"summer vacation Archives - I See Me! Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/","og_locale":"en_US","og_type":"article","og_title":"summer vacation Archives","og_url":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/","og_site_name":"I See Me! Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/","url":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/","name":"summer vacation Archives - I See Me! Blog","isPartOf":{"@id":"https:\/\/wordpress.iseeme.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/wordpress.iseeme.com\/blog\/tag\/summer-vacation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wordpress.iseeme.com\/blog\/"},{"@type":"ListItem","position":2,"name":"summer vacation"}]},{"@type":"WebSite","@id":"https:\/\/wordpress.iseeme.com\/blog\/#website","url":"https:\/\/wordpress.iseeme.com\/blog\/","name":"I See Me! Blog","description":"Personalized books for kids!","publisher":{"@id":"https:\/\/wordpress.iseeme.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wordpress.iseeme.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/wordpress.iseeme.com\/blog\/#organization","name":"I See Me! Blog","url":"https:\/\/wordpress.iseeme.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/wordpress.iseeme.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/wordpress.iseeme.com\/wp-content\/uploads\/2023\/08\/ism_logo_500.png","contentUrl":"https:\/\/wordpress.iseeme.com\/wp-content\/uploads\/2023\/08\/ism_logo_500.png","width":512,"height":512,"caption":"I See Me! Blog"},"image":{"@id":"https:\/\/wordpress.iseeme.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ISeeMeBooks","https:\/\/www.instagram.com\/iseemebooks\/"]}]}},"_links":{"self":[{"href":"https:\/\/wordpress.iseeme.com\/blog\/wp-json\/wp\/v2\/tags\/1860"}],"collection":[{"href":"https:\/\/wordpress.iseeme.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/wordpress.iseeme.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/wordpress.iseeme.com\/blog\/wp-json\/wp\/v2\/posts?tags=1860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}